{"id":3598,"date":"2023-11-06T10:00:00","date_gmt":"2023-11-06T13:00:00","guid":{"rendered":"https:\/\/exponor.cl\/?p=3598"},"modified":"2024-04-11T16:42:20","modified_gmt":"2024-04-11T19:42:20","slug":"presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial","status":"publish","type":"post","link":"https:\/\/exponor.cl\/en\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/","title":{"rendered":"President of Escondida | BHP: \"EXPONOR, one of the most important mining exhibitions worlwide\""},"content":{"rendered":"<p class=\"wp-block-paragraph\"><em>The mining company was one of the first to be part of EXPONOR, in which it currently participates as a strategic partner<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Minera Escondida Limitada, currently Escondida | BHP, has participated as a strategic partner since the first EXPONOR in 1995, which positions it as the first mining company to play a leading role in this international event, which will hold its 20th edition in 2024.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-color is-layout-flow wp-block-quote-is-layout-flow\" style=\"color:#0096d7\">\n<p class=\"wp-block-paragraph\">\u201c<em>In June 2024, a new edition of EXPONOR will be held, one of the most important mining exhibitions worldwide, promoted by the Antofagasta Industrial Association, AIA. As every year, Escondida | BHP will participate, reaffirming our commitment to the productive development of the Antofagasta Region and, especially, to local suppliers and the communities that we are a part of<\/em>\", said Alejandro Tapia, President of Escondida | BHP.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">The company is currently working on its investment projects for the period 2030 - 2040, in the areas of mining, cathodes, concentrators and NPI&amp;CHO. In the first section, there are autonomous truck investment projects to increase the fleet by 2025, also projects involving mine dehydration, together with energy and water efficiency projects, in the short term.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">These initiatives arise from the commitment of Escondida | BHP to reduce the carbon footprint of its operations, with more sustainable processes over time and to contribute to the environment, people, economic development, and communities.<\/p>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#2c4d98;font-size:30px\"><strong>EXPONOR, the right place<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-color is-layout-flow wp-block-quote-is-layout-flow\" style=\"color:#0096d7\">\n<p class=\"wp-block-paragraph\">\u201c<em>We are aware of Escondida | BHP's contribution to transforming the industry based on innovation, operational excellence, safety, and a diverse workforce that is prepared for the future. And EXPONOR 2024 will be a great place to share these visions, make business opportunities visible and project from Chile the mining of the future that we are building together. See you in June 2024<\/em>\", said the mining executive.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Escondida | BHP is characterized by an active participation in the various activities carried out and offered by EXPONOR, such as visits by technical delegations, business meetings, seminars, worksite visits, among others, since it recognizes EXPONOR as an event of great importance to the industry, where mining companies meet to showcase their best and find new technologies and innovations that they and the market require.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EXPONOR 2024 -june 3 \u2013 6, 2024- has the support of its strategic partners Albemarle, Antofagasta Minerals, CODELCO, Escondida|BHP, GLENCORE, Minera El Abra, Pan American Silver, Sierra Gorda SCM, Spence|BHP and SQM, together with the backing of APRIMIN, Consejo Minero, Generadoras de Chile, InvestChile, the Ministries of Economy, Mining and Energy, the Regional Government, ProChile, SOFOFA and SONAMI. Official media partners are Miner\u00eda Chilena, Reporte Minero and El Mercurio de Antofagasta. Stands can be reserved at: reservas@exponor.cl - 552 454 335.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EXPONOR 2024... Solutions for a sustainable industry.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\">Antofagasta, november 06, 2023.<\/p>","protected":false},"excerpt":{"rendered":"<p>La compa\u00f1\u00eda minera fue una de las primeras en ser parte de EXPONOR, en la que actualmente participa como socio estrat\u00e9gico. Desde la primera EXPONOR, en el a\u00f1o 1995, que participa como socio estrat\u00e9gico Minera Escondida Limitada, actualmente Escondida | BHP, lo que la posiciona como la primera minera en protagonizar este evento internacional, que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5323,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[36,21,35,33],"tags":[43,42,44],"class_list":["post-3598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chile","category-exponor2024","category-industria-verde","category-mineria","tag-bhp","tag-escondidabhp","tag-exponor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presidente ESCONDIDA | BHP: \u201cEXPONOR, una de las exhibiciones mineras m\u00e1s importantes a nivel mundial&quot; - EXPONOR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exponor.cl\/en\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente ESCONDIDA | BHP: \u201cEXPONOR, una de las exhibiciones mineras m\u00e1s importantes a nivel mundial&quot; - EXPONOR\" \/>\n<meta property=\"og:description\" content=\"La compa\u00f1\u00eda minera fue una de las primeras en ser parte de EXPONOR, en la que actualmente participa como socio estrat\u00e9gico. Desde la primera EXPONOR, en el a\u00f1o 1995, que participa como socio estrat\u00e9gico Minera Escondida Limitada, actualmente Escondida | BHP, lo que la posiciona como la primera minera en protagonizar este evento internacional, que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exponor.cl\/en\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/\" \/>\n<meta property=\"og:site_name\" content=\"EXPONOR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/exponorcl\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-06T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-11T19:42:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exponor.cl\/wp-content\/uploads\/2024\/04\/Fotos-Web-4_Mesa-de-trabajo-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1184\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@exponorcl\" \/>\n<meta name=\"twitter:site\" content=\"@exponorcl\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/2023\\\/11\\\/06\\\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2023\\\/11\\\/06\\\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/person\\\/f43dbb34f0c1563f0a03fb8fae81a53b\"},\"headline\":\"Presidente ESCONDIDA | BHP: \u201cEXPONOR, una de las exhibiciones mineras m\u00e1s importantes a nivel mundial&#8221;\",\"datePublished\":\"2023-11-06T13:00:00+00:00\",\"dateModified\":\"2024-04-11T19:42:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2023\\\/11\\\/06\\\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\\\/\"},\"wordCount\":497,\"publisher\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2023\\\/11\\\/06\\\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Fotos-Web-4_Mesa-de-trabajo-1-scaled.jpg\",\"keywords\":[\"BHP\",\"EscondidaBHP\",\"EXPONOR\"],\"articleSection\":[\"Chile\",\"EXPONOR2024\",\"IndustriaVerde\",\"Miner\u00eda\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/2023\\\/11\\\/06\\\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\\\/\",\"url\":\"https:\\\/\\\/exponor.cl\\\/2023\\\/11\\\/06\\\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\\\/\",\"name\":\"Presidente ESCONDIDA | BHP: \u201cEXPONOR, una de las exhibiciones mineras m\u00e1s importantes a nivel mundial\\\" - EXPONOR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2023\\\/11\\\/06\\\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2023\\\/11\\\/06\\\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Fotos-Web-4_Mesa-de-trabajo-1-scaled.jpg\",\"datePublished\":\"2023-11-06T13:00:00+00:00\",\"dateModified\":\"2024-04-11T19:42:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2023\\\/11\\\/06\\\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exponor.cl\\\/2023\\\/11\\\/06\\\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/2023\\\/11\\\/06\\\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Fotos-Web-4_Mesa-de-trabajo-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Fotos-Web-4_Mesa-de-trabajo-1-scaled.jpg\",\"width\":2560,\"height\":1184},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/2023\\\/11\\\/06\\\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exponor.cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidente ESCONDIDA | BHP: \u201cEXPONOR, una de las exhibiciones mineras m\u00e1s importantes a nivel mundial&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#website\",\"url\":\"https:\\\/\\\/exponor.cl\\\/\",\"name\":\"EXPONOR\",\"description\":\"Exhibici\u00f3n Internacional de Tecnolog\u00edas e Innovaciones para la Industria Minera y Energ\u00e9tica\",\"publisher\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exponor.cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#organization\",\"name\":\"EXPONOR\",\"url\":\"https:\\\/\\\/exponor.cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/EXPONOR2026_confecha.png\",\"contentUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/EXPONOR2026_confecha.png\",\"width\":2107,\"height\":1061,\"caption\":\"EXPONOR\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/exponorcl\",\"https:\\\/\\\/x.com\\\/exponorcl\",\"https:\\\/\\\/cl.linkedin.com\\\/company\\\/exponorcl\",\"https:\\\/\\\/www.instagram.com\\\/exponorcl\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/person\\\/f43dbb34f0c1563f0a03fb8fae81a53b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/exponor.cl\"],\"url\":\"https:\\\/\\\/exponor.cl\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente ESCONDIDA | BHP: \u201cEXPONOR, una de las exhibiciones mineras m\u00e1s importantes a nivel mundial\" - EXPONOR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exponor.cl\/en\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/","og_locale":"en_US","og_type":"article","og_title":"Presidente ESCONDIDA | BHP: \u201cEXPONOR, una de las exhibiciones mineras m\u00e1s importantes a nivel mundial\" - EXPONOR","og_description":"La compa\u00f1\u00eda minera fue una de las primeras en ser parte de EXPONOR, en la que actualmente participa como socio estrat\u00e9gico. Desde la primera EXPONOR, en el a\u00f1o 1995, que participa como socio estrat\u00e9gico Minera Escondida Limitada, actualmente Escondida | BHP, lo que la posiciona como la primera minera en protagonizar este evento internacional, que [&hellip;]","og_url":"https:\/\/exponor.cl\/en\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/","og_site_name":"EXPONOR","article_publisher":"https:\/\/facebook.com\/exponorcl","article_published_time":"2023-11-06T13:00:00+00:00","article_modified_time":"2024-04-11T19:42:20+00:00","og_image":[{"width":2560,"height":1184,"url":"https:\/\/exponor.cl\/wp-content\/uploads\/2024\/04\/Fotos-Web-4_Mesa-de-trabajo-1-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@exponorcl","twitter_site":"@exponorcl","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exponor.cl\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/#article","isPartOf":{"@id":"https:\/\/exponor.cl\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/"},"author":{"name":"admin","@id":"https:\/\/exponor.cl\/#\/schema\/person\/f43dbb34f0c1563f0a03fb8fae81a53b"},"headline":"Presidente ESCONDIDA | BHP: \u201cEXPONOR, una de las exhibiciones mineras m\u00e1s importantes a nivel mundial&#8221;","datePublished":"2023-11-06T13:00:00+00:00","dateModified":"2024-04-11T19:42:20+00:00","mainEntityOfPage":{"@id":"https:\/\/exponor.cl\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/"},"wordCount":497,"publisher":{"@id":"https:\/\/exponor.cl\/#organization"},"image":{"@id":"https:\/\/exponor.cl\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/#primaryimage"},"thumbnailUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2024\/04\/Fotos-Web-4_Mesa-de-trabajo-1-scaled.jpg","keywords":["BHP","EscondidaBHP","EXPONOR"],"articleSection":["Chile","EXPONOR2024","IndustriaVerde","Miner\u00eda"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/exponor.cl\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/","url":"https:\/\/exponor.cl\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/","name":"Presidente ESCONDIDA | BHP: \u201cEXPONOR, una de las exhibiciones mineras m\u00e1s importantes a nivel mundial\" - EXPONOR","isPartOf":{"@id":"https:\/\/exponor.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exponor.cl\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/#primaryimage"},"image":{"@id":"https:\/\/exponor.cl\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/#primaryimage"},"thumbnailUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2024\/04\/Fotos-Web-4_Mesa-de-trabajo-1-scaled.jpg","datePublished":"2023-11-06T13:00:00+00:00","dateModified":"2024-04-11T19:42:20+00:00","breadcrumb":{"@id":"https:\/\/exponor.cl\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exponor.cl\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/exponor.cl\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/#primaryimage","url":"https:\/\/exponor.cl\/wp-content\/uploads\/2024\/04\/Fotos-Web-4_Mesa-de-trabajo-1-scaled.jpg","contentUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2024\/04\/Fotos-Web-4_Mesa-de-trabajo-1-scaled.jpg","width":2560,"height":1184},{"@type":"BreadcrumbList","@id":"https:\/\/exponor.cl\/2023\/11\/06\/presidente-escondida-bhp-exponor-una-de-las-exhibiciones-mineras-mas-importantes-a-nivel-mundial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exponor.cl\/"},{"@type":"ListItem","position":2,"name":"Presidente ESCONDIDA | BHP: \u201cEXPONOR, una de las exhibiciones mineras m\u00e1s importantes a nivel mundial&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/exponor.cl\/#website","url":"https:\/\/exponor.cl\/","name":"EXPONOR","description":"Exhibici\u00f3n Internacional de Tecnolog\u00edas e Innovaciones para la Industria Minera y Energ\u00e9tica","publisher":{"@id":"https:\/\/exponor.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exponor.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/exponor.cl\/#organization","name":"EXPONOR","url":"https:\/\/exponor.cl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/exponor.cl\/#\/schema\/logo\/image\/","url":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/03\/EXPONOR2026_confecha.png","contentUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/03\/EXPONOR2026_confecha.png","width":2107,"height":1061,"caption":"EXPONOR"},"image":{"@id":"https:\/\/exponor.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/exponorcl","https:\/\/x.com\/exponorcl","https:\/\/cl.linkedin.com\/company\/exponorcl","https:\/\/www.instagram.com\/exponorcl\/"]},{"@type":"Person","@id":"https:\/\/exponor.cl\/#\/schema\/person\/f43dbb34f0c1563f0a03fb8fae81a53b","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/exponor.cl"],"url":"https:\/\/exponor.cl\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts\/3598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/comments?post=3598"}],"version-history":[{"count":3,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts\/3598\/revisions"}],"predecessor-version":[{"id":3938,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts\/3598\/revisions\/3938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/media\/5323"}],"wp:attachment":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/media?parent=3598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/categories?post=3598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/tags?post=3598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}