{"id":28212,"date":"2026-05-14T10:30:49","date_gmt":"2026-05-14T13:30:49","guid":{"rendered":"https:\/\/exponor.cl\/?p=28212"},"modified":"2026-05-14T18:54:31","modified_gmt":"2026-05-14T21:54:31","slug":"todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026","status":"publish","type":"post","link":"https:\/\/exponor.cl\/en\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/","title":{"rendered":"Todo lo que necesitas saber para tu visita a EXPONOR 2026"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p style=\"text-align: justify;\"><em>La XXI Edici\u00f3n de la Exhibici\u00f3n Internacional de Tecnolog\u00edas e Innovaciones para la Industria Minera y Energ\u00e9tica, que se realizar\u00e1 entre el 8 y el 11 de junio pr\u00f3ximos, ser\u00e1 la m\u00e1s grande registrada en su historia, raz\u00f3n por la cual la organizaci\u00f3n prepara, a trav\u00e9s de su <strong>Gu\u00eda de Visitantes<\/strong>, una experiencia integral que considera informaci\u00f3n clave para visitantes y expositores.<\/em><\/p>\n<p style=\"text-align: justify;\">Desde su primera versi\u00f3nbajo el nombre de EXPONOR en 1995, ha experimentado una sostenida evoluci\u00f3n que la ha posicionado entre las tres exhibiciones mineras y energ\u00e9ticas m\u00e1s importantes del mundo. En ese contexto, la edici\u00f3n 2026 ha sido preparada minuciosamente durante los dos a\u00f1os previos a su realizaci\u00f3n, reflejando el alto est\u00e1ndar y alcance internacional que caracteriza a esta nueva versi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Para esta edici\u00f3n, se proyecta la llegada de cerca de 47 mil visitantes, quienes se alojar\u00e1n durante la semana en distintos puntos de Antofagasta. Por esta raz\u00f3n y con el objetivo de facilitar una experiencia c\u00f3moda, eficiente y organizada, EXPONOR elabor\u00f3 una completa Gu\u00eda del Visitante, documento que reunir\u00e1 toda la informaci\u00f3n necesaria para quienes asistan al evento.<\/p>\n<p style=\"text-align: justify;\">Entre los contenidos disponibles se incluyen horarios de exhibici\u00f3n; un c\u00f3digo QR para revisar el programa y las ubicaciones de las actividades; informaci\u00f3n sobre la distribuci\u00f3n de las principales compa\u00f1\u00edas mineras; alternativas gastron\u00f3micas dentro del recinto; adem\u00e1s de indicaciones para acceder en veh\u00edculo particular y detalles sobre estacionamientos; opciones de transporte p\u00fablico; buses de acercamiento para visitantes y expositores; y otros servicios de inter\u00e9s que permitir\u00e1n planificar la visita con anticipaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">En este contexto, una de las empresas colaboradoras en materia de transporte ser\u00e1 Green Energy Transport, organizaci\u00f3n comprometida con el desarrollo de soluciones de movilidad para la miner\u00eda y la energ\u00eda. <em>\u201cExponor constituye una plataforma clave para que empresas regionales como la nuestra puedan visibilizar su experiencia, fortalecer sus redes estrat\u00e9gicas y participar activamente en los desaf\u00edos futuros de la industria, especialmente en materias de electromovilidad, sostenibilidad y log\u00edstica para la gran miner\u00eda\u201d<\/em>, expres\u00f3 la directora de Green Energy Transport, Valentina M\u00e9ndez.<\/p>\n<p style=\"text-align: justify;\">Asimismo, Wladimir Valladares, coordinador general de Brinner Service, empresa antofagastina del rubro gastron\u00f3mico, mencion\u00f3 que <em>\u201cpara Exponor 2026 queremos transformar la pausa del caf\u00e9 en una experiencia. M\u00e1s que una cafeter\u00eda, buscamos crear un punto de encuentro dentro de la exposici\u00f3n: un espacio donde converjan las conversaciones, los negocios y las experiencias alrededor de un caf\u00e9 preparado por profesionales\u201d.<\/em><\/p>\n<p style=\"text-align: justify;\">En la misma l\u00ednea, EXPONOR 2026 contar\u00e1 con puntos de hidrataci\u00f3n a cargo de la empresa antofagastina Puri, dedicada a la elaboraci\u00f3n de agua purificada y alcalina. Esta colaboraci\u00f3n busca seguir impulsando el desarrollo econ\u00f3mico regional mediante alianzas con proveedores locales de identidad sostenible, alineados con los criterios ESG (Ambiental, Social y de Gobernanza) que hoy exige la industria minera. Junto a ello, Puri destaca por su aporte en materia de reinserci\u00f3n social. <em>\u201cEntregamos oportunidades laborales en la elaboraci\u00f3n y producci\u00f3n de agua purificada y alcalina, siendo un ejemplo en Chile y Latinoam\u00e9rica, al trabajar dentro de un recinto penitenciario en el sector La Negra de Antofagasta\u201d<\/em>, agreg\u00f3 la gerente t\u00e9cnico del \u00e1rea de Ingenier\u00eda de Alimentos, Mar\u00eda Soledad Garc\u00eda.<\/p>\n<p style=\"text-align: justify;\">Andrea Moreno, gerente de EXPONOR, sostuvo que <em>\u201cla versi\u00f3n 2026 de EXPONOR ser\u00e1 la m\u00e1s grande registrada en nuestra historia, por esta raz\u00f3n, es esencial el encadenamiento con todos los sectores que mueven la econom\u00eda, desde nuestra regi\u00f3n, hasta los actores internacionales. Estamos orgullosos de afirmar que esta exhibici\u00f3n es el punto donde se generan los v\u00ednculos que impulsan la econom\u00eda mundial\u201d.<\/em><\/p>\n<p style=\"text-align: justify;\">La organizaci\u00f3n inform\u00f3 que la Gu\u00eda del Visitante ser\u00e1 compartida durante los pr\u00f3ximos d\u00edas a trav\u00e9s de las plataformas oficiales de EXPONOR, permitiendo que asistentes, expositores y delegaciones nacionales e internacionales puedan preparar con anticipaci\u00f3n su participaci\u00f3n en el principal encuentro minero y energ\u00e9tico del a\u00f1o.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La XXI Edici\u00f3n de la Exhibici\u00f3n Internacional de Tecnolog\u00edas e Innovaciones para la Industria Minera y Energ\u00e9tica, que se realizar\u00e1 entre el 8 y el 11 de junio pr\u00f3ximos, ser\u00e1 la m\u00e1s grande registrada en su historia, raz\u00f3n por la cual la organizaci\u00f3n prepara, a trav\u00e9s de su Gu\u00eda de Visitantes, una experiencia integral que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28213,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[38,49],"tags":[],"class_list":["post-28212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antofagasta","category-exponor2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Todo lo que necesitas saber para tu visita a EXPONOR 2026 - EXPONOR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exponor.cl\/en\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todo lo que necesitas saber para tu visita a EXPONOR 2026 - EXPONOR\" \/>\n<meta property=\"og:description\" content=\"La XXI Edici\u00f3n de la Exhibici\u00f3n Internacional de Tecnolog\u00edas e Innovaciones para la Industria Minera y Energ\u00e9tica, que se realizar\u00e1 entre el 8 y el 11 de junio pr\u00f3ximos, ser\u00e1 la m\u00e1s grande registrada en su historia, raz\u00f3n por la cual la organizaci\u00f3n prepara, a trav\u00e9s de su Gu\u00eda de Visitantes, una experiencia integral que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exponor.cl\/en\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"EXPONOR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/exponorcl\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-14T13:30:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-14T21:54:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exponor.cl\/wp-content\/uploads\/2026\/05\/general_exponor-1280x720-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@exponorcl\" \/>\n<meta name=\"twitter:site\" content=\"@exponorcl\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/person\\\/f43dbb34f0c1563f0a03fb8fae81a53b\"},\"headline\":\"Todo lo que necesitas saber para tu visita a EXPONOR 2026\",\"datePublished\":\"2026-05-14T13:30:49+00:00\",\"dateModified\":\"2026-05-14T21:54:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/\"},\"wordCount\":824,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/general_exponor-1280x720-1.jpg\",\"articleSection\":[\"Antofagasta\",\"EXPONOR2026\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/\",\"url\":\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/\",\"name\":\"Todo lo que necesitas saber para tu visita a EXPONOR 2026 - EXPONOR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/general_exponor-1280x720-1.jpg\",\"datePublished\":\"2026-05-14T13:30:49+00:00\",\"dateModified\":\"2026-05-14T21:54:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/general_exponor-1280x720-1.jpg\",\"contentUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/general_exponor-1280x720-1.jpg\",\"width\":1280,\"height\":592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/2026\\\/05\\\/14\\\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exponor.cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todo lo que necesitas saber para tu visita a EXPONOR 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#website\",\"url\":\"https:\\\/\\\/exponor.cl\\\/\",\"name\":\"EXPONOR\",\"description\":\"Exhibici\u00f3n Internacional de Tecnolog\u00edas e Innovaciones para la Industria Minera y Energ\u00e9tica\",\"publisher\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exponor.cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#organization\",\"name\":\"EXPONOR\",\"url\":\"https:\\\/\\\/exponor.cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/EXPONOR2026_confecha.png\",\"contentUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/EXPONOR2026_confecha.png\",\"width\":2107,\"height\":1061,\"caption\":\"EXPONOR\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/exponorcl\",\"https:\\\/\\\/x.com\\\/exponorcl\",\"https:\\\/\\\/cl.linkedin.com\\\/company\\\/exponorcl\",\"https:\\\/\\\/www.instagram.com\\\/exponorcl\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/person\\\/f43dbb34f0c1563f0a03fb8fae81a53b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/exponor.cl\"],\"url\":\"https:\\\/\\\/exponor.cl\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todo lo que necesitas saber para tu visita a EXPONOR 2026 - EXPONOR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exponor.cl\/en\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/","og_locale":"en_US","og_type":"article","og_title":"Todo lo que necesitas saber para tu visita a EXPONOR 2026 - EXPONOR","og_description":"La XXI Edici\u00f3n de la Exhibici\u00f3n Internacional de Tecnolog\u00edas e Innovaciones para la Industria Minera y Energ\u00e9tica, que se realizar\u00e1 entre el 8 y el 11 de junio pr\u00f3ximos, ser\u00e1 la m\u00e1s grande registrada en su historia, raz\u00f3n por la cual la organizaci\u00f3n prepara, a trav\u00e9s de su Gu\u00eda de Visitantes, una experiencia integral que [&hellip;]","og_url":"https:\/\/exponor.cl\/en\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/","og_site_name":"EXPONOR","article_publisher":"https:\/\/facebook.com\/exponorcl","article_published_time":"2026-05-14T13:30:49+00:00","article_modified_time":"2026-05-14T21:54:31+00:00","og_image":[{"width":1280,"height":592,"url":"https:\/\/exponor.cl\/wp-content\/uploads\/2026\/05\/general_exponor-1280x720-1.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@exponorcl","twitter_site":"@exponorcl","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/#article","isPartOf":{"@id":"https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/"},"author":{"name":"admin","@id":"https:\/\/exponor.cl\/#\/schema\/person\/f43dbb34f0c1563f0a03fb8fae81a53b"},"headline":"Todo lo que necesitas saber para tu visita a EXPONOR 2026","datePublished":"2026-05-14T13:30:49+00:00","dateModified":"2026-05-14T21:54:31+00:00","mainEntityOfPage":{"@id":"https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/"},"wordCount":824,"commentCount":0,"publisher":{"@id":"https:\/\/exponor.cl\/#organization"},"image":{"@id":"https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2026\/05\/general_exponor-1280x720-1.jpg","articleSection":["Antofagasta","EXPONOR2026"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/","url":"https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/","name":"Todo lo que necesitas saber para tu visita a EXPONOR 2026 - EXPONOR","isPartOf":{"@id":"https:\/\/exponor.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/#primaryimage"},"image":{"@id":"https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2026\/05\/general_exponor-1280x720-1.jpg","datePublished":"2026-05-14T13:30:49+00:00","dateModified":"2026-05-14T21:54:31+00:00","breadcrumb":{"@id":"https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/#primaryimage","url":"https:\/\/exponor.cl\/wp-content\/uploads\/2026\/05\/general_exponor-1280x720-1.jpg","contentUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2026\/05\/general_exponor-1280x720-1.jpg","width":1280,"height":592},{"@type":"BreadcrumbList","@id":"https:\/\/exponor.cl\/2026\/05\/14\/todo-lo-que-necesitas-saber-para-tu-visita-a-exponor-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exponor.cl\/"},{"@type":"ListItem","position":2,"name":"Todo lo que necesitas saber para tu visita a EXPONOR 2026"}]},{"@type":"WebSite","@id":"https:\/\/exponor.cl\/#website","url":"https:\/\/exponor.cl\/","name":"EXPONOR","description":"Exhibici\u00f3n Internacional de Tecnolog\u00edas e Innovaciones para la Industria Minera y Energ\u00e9tica","publisher":{"@id":"https:\/\/exponor.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exponor.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/exponor.cl\/#organization","name":"EXPONOR","url":"https:\/\/exponor.cl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/exponor.cl\/#\/schema\/logo\/image\/","url":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/03\/EXPONOR2026_confecha.png","contentUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/03\/EXPONOR2026_confecha.png","width":2107,"height":1061,"caption":"EXPONOR"},"image":{"@id":"https:\/\/exponor.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/exponorcl","https:\/\/x.com\/exponorcl","https:\/\/cl.linkedin.com\/company\/exponorcl","https:\/\/www.instagram.com\/exponorcl\/"]},{"@type":"Person","@id":"https:\/\/exponor.cl\/#\/schema\/person\/f43dbb34f0c1563f0a03fb8fae81a53b","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/exponor.cl"],"url":"https:\/\/exponor.cl\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts\/28212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/comments?post=28212"}],"version-history":[{"count":6,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts\/28212\/revisions"}],"predecessor-version":[{"id":28267,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts\/28212\/revisions\/28267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/media\/28213"}],"wp:attachment":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/media?parent=28212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/categories?post=28212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/tags?post=28212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}