{"id":26544,"date":"2025-11-06T16:48:46","date_gmt":"2025-11-06T19:48:46","guid":{"rendered":"https:\/\/exponor.cl\/?p=26544"},"modified":"2025-11-06T16:48:46","modified_gmt":"2025-11-06T19:48:46","slug":"exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales","status":"publish","type":"post","link":"https:\/\/exponor.cl\/en\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/","title":{"rendered":"EXPONOR showcases Chilean mining to the world with a strong presence at international exhibitions"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; theme_builder_area=&#8221;post_content&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;20px|||||&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221; da_disable_devices=&#8221;off|off|off&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p style=\"text-align: justify;\">La exhibici\u00f3n minero-energ\u00e9tica m\u00e1s importante del pr\u00f3ximo a\u00f1o ha fortalecido su posici\u00f3n global participando en diversos eventos internacionales, promoviendo los avances, la inversi\u00f3n y las oportunidades de colaboraci\u00f3n en la industria minera que se encontrar\u00e1n en EXPONOR 2026.<\/p>\n<p style=\"text-align: justify;\">Organizada por la Asociaci\u00f3n de Industriales de Antofagasta (AIA), el evento contin\u00faa consolid\u00e1ndose como una plataforma estrat\u00e9gica para la proyecci\u00f3n de la miner\u00eda chilena a nivel global. En los \u00faltimos meses, representantes de EXPONOR han participado activamente en eventos internacionales de gran relevancia como <strong>Imarc (Australia)<\/strong> y la vecina <strong>Perumin (Per\u00fa).<\/strong><\/p>\n<p style=\"text-align: justify;\">La presencia de EXPONOR en ferias internacionales ha permitido fortalecer alianzas con entidades de promoci\u00f3n econ\u00f3mica, c\u00e1maras de comercio y asociaciones mineras, potenciando los lazos comerciales y t\u00e9cnicos. \u201c<em>Nuestro objetivo es posicionar al pa\u00eds como el epicentro mundial de los negocios mineros y energ\u00e9ticos. En nuestra exhibici\u00f3n, Chile demuestra su liderazgo en innovaci\u00f3n, sostenibilidad y desarrollo tecnol\u00f3gico<\/em>\u201d, se\u00f1al\u00f3 Andrea Moreno, gerente del evento.<\/p>\n<p style=\"text-align: justify;\">Dentro de estas ferias, se reforzaron las relaciones con la embajada de Canad\u00e1, pa\u00eds invitado de honor de la exhibici\u00f3n. Su embajadora, Karolina Guay, coment\u00f3 <em>\u201cestoy muy agradecida de EXPONOR 2026 por invitarnos como pa\u00eds de honor. Muy emocionados de tener a varias compa\u00f1\u00edas, empresas canadienses presentes que van a poder promover soluciones innovadoras para una miner\u00eda m\u00e1s verde\u201d.<\/em><\/p>\n<p style=\"text-align: justify;\">Esto demuestra la colaboraci\u00f3n entre Canad\u00e1 y Chile, donde el pa\u00eds norteamericano destaca como mayor inversionista extranjero en nuestro pa\u00eds, m\u00e1s del 50% de estas inversiones en miner\u00eda. Adem\u00e1s, EXPONOR participar\u00e1 en la PDAC 2026, donde cerraran los \u00faltimos acuerdos de cara a la 21 edici\u00f3n de la exhibici\u00f3n nacional.<\/p>\n<p style=\"text-align: justify;\">Australia es otra de las comisiones que ha dicho presente dentro de los pa\u00edses participantes de la exhibici\u00f3n. Andrew Martin, embajador para Chile y Ecuador, quien asumi\u00f3 su cargo tras la realizaci\u00f3n de la edici\u00f3n 2024, se\u00f1ala su entusiasmo por participar por primera vez en la exhibici\u00f3n<em> \u201che escuchado de EXPONOR durante muchos a\u00f1os en mi trabajo diplom\u00e1tico.<\/em> <em>Es una exhibici\u00f3n de gran relevancia, no solo en Chile, sino tambi\u00e9n a nivel mundial. Por parte de las empresas australianas hay mucho inter\u00e9s y mucho entusiasmo por ser parte de EXPONOR 2026\u201d.<\/em><\/p>\n<h3 style=\"text-align: justify;\"><strong>Ejes centrales de la exhibici\u00f3n minero-energ\u00e9tica<\/strong><\/h3>\n<p style=\"text-align: justify;\">Durante estas instancias, la delegaci\u00f3n de EXPONOR ha potenciado el compromiso del evento con la <strong>tecnolog\u00eda, la automatizaci\u00f3n y la sostenibilidad ambiental<\/strong>, pilares fundamentales del futuro minero y energ\u00e9tico. Asimismo, se ha promovido la 21\u00b0 edici\u00f3n de la exhibici\u00f3n como un espacio para fomentar la transferencia tecnol\u00f3gica y la vinculaci\u00f3n entre empresas proveedoras, inversionistas y empresas l\u00edderes mundiales ubicadas en el epicentro minero global.<\/p>\n<p style=\"text-align: justify;\">Con estas gestiones internacionales, EXPONOR busca atraer una participaci\u00f3n r\u00e9cord de empresas extranjeras en su pr\u00f3xima versi\u00f3n, proyectando 1.200 expositores de 30 pa\u00edses y 16 pabellones internacionales para este 2026. Adem\u00e1s, se reafirma el compromiso de la Regi\u00f3n de Antofagasta con la diversificaci\u00f3n, la innovaci\u00f3n y el liderazgo minero mundial.<\/p>\n<h3 style=\"text-align: justify;\"><strong>Conecta con los l\u00edderes del sector en EXPONOR 2026<\/strong><\/h3>\n<p style=\"text-align: justify;\">La pr\u00f3xima edici\u00f3n de EXPONOR se llevar\u00e1 a cabo entre el 8 y el 11 de junio de 2026. El evento cuenta con destacados socios estrat\u00e9gicos, como\u00a0<strong>Albemarle, Antofagasta Minerals, Capstone Copper, CODELCO, El Abra, Escondida | BHP, Glencore, Pampa Norte | BHP, Sierra Gorda SCM y SQM.<\/strong><\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, es patrocinado por entidades clave como\u00a0<strong>APRIMIN, Consejo Minero, Generadoras, InvestChile, Ministerio de Miner\u00eda, Ministerio de Econom\u00eda, Fomento y Turismo, Ministerio de Energ\u00eda, ProChile, SOFOFA y SONAMI<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Para m\u00e1s detalles, sigue sus redes sociales o consulta los medios oficiales como Miner\u00eda Chilena, Reporte Minero y El Mercurio de Antofagasta. No pierdas la oportunidad de ser parte de esta gran cita minera y energ\u00e9tica.<\/p>\n<p style=\"text-align: justify;\">Reserva tu stand hoy mismo en\u00a0<a href=\"http:\/\/www.exponor.cl\/\">www.exponor.cl<\/a>\u00a0o escribe a\u00a0<a href=\"mailto:reservas@exponor.cl\">reservas@exponor.cl<\/a>\u00a0y s\u00e9 parte de la transformaci\u00f3n minera global.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La exhibici\u00f3n minero-energ\u00e9tica m\u00e1s importante del pr\u00f3ximo a\u00f1o ha fortalecido su posici\u00f3n global participando en diversos eventos internacionales, promoviendo los avances, la inversi\u00f3n y las oportunidades de colaboraci\u00f3n en la industria minera que se encontrar\u00e1n en EXPONOR 2026. Organizada por la Asociaci\u00f3n de Industriales de Antofagasta (AIA), el evento contin\u00faa consolid\u00e1ndose como una plataforma estrat\u00e9gica [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26087,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[38,20,49],"tags":[],"class_list":["post-26544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-antofagasta","category-exhibicion","category-exponor2026"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EXPONOR proyecta la miner\u00eda chilena al mundo con destacada presencia en exhibiciones internacionales - EXPONOR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exponor.cl\/en\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EXPONOR proyecta la miner\u00eda chilena al mundo con destacada presencia en exhibiciones internacionales - EXPONOR\" \/>\n<meta property=\"og:description\" content=\"La exhibici\u00f3n minero-energ\u00e9tica m\u00e1s importante del pr\u00f3ximo a\u00f1o ha fortalecido su posici\u00f3n global participando en diversos eventos internacionales, promoviendo los avances, la inversi\u00f3n y las oportunidades de colaboraci\u00f3n en la industria minera que se encontrar\u00e1n en EXPONOR 2026. Organizada por la Asociaci\u00f3n de Industriales de Antofagasta (AIA), el evento contin\u00faa consolid\u00e1ndose como una plataforma estrat\u00e9gica [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exponor.cl\/en\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/\" \/>\n<meta property=\"og:site_name\" content=\"EXPONOR\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/exponorcl\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-06T19:48:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/08\/Bandera2026.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@exponorcl\" \/>\n<meta name=\"twitter:site\" content=\"@exponorcl\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/person\\\/f43dbb34f0c1563f0a03fb8fae81a53b\"},\"headline\":\"EXPONOR proyecta la miner\u00eda chilena al mundo con destacada presencia en exhibiciones internacionales\",\"datePublished\":\"2025-11-06T19:48:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/\"},\"wordCount\":810,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Bandera2026.png\",\"articleSection\":[\"Antofagasta\",\"Exhibici\u00f3n\",\"EXPONOR2026\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/\",\"url\":\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/\",\"name\":\"EXPONOR proyecta la miner\u00eda chilena al mundo con destacada presencia en exhibiciones internacionales - EXPONOR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Bandera2026.png\",\"datePublished\":\"2025-11-06T19:48:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Bandera2026.png\",\"contentUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/Bandera2026.png\",\"width\":800,\"height\":370},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/2025\\\/11\\\/06\\\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exponor.cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EXPONOR proyecta la miner\u00eda chilena al mundo con destacada presencia en exhibiciones internacionales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#website\",\"url\":\"https:\\\/\\\/exponor.cl\\\/\",\"name\":\"EXPONOR\",\"description\":\"Exhibici\u00f3n Internacional de Tecnolog\u00edas e Innovaciones para la Industria Minera y Energ\u00e9tica\",\"publisher\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exponor.cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#organization\",\"name\":\"EXPONOR\",\"url\":\"https:\\\/\\\/exponor.cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/EXPONOR2026_confecha.png\",\"contentUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/EXPONOR2026_confecha.png\",\"width\":2107,\"height\":1061,\"caption\":\"EXPONOR\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/exponorcl\",\"https:\\\/\\\/x.com\\\/exponorcl\",\"https:\\\/\\\/cl.linkedin.com\\\/company\\\/exponorcl\",\"https:\\\/\\\/www.instagram.com\\\/exponorcl\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/person\\\/f43dbb34f0c1563f0a03fb8fae81a53b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/exponor.cl\"],\"url\":\"https:\\\/\\\/exponor.cl\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EXPONOR proyecta la miner\u00eda chilena al mundo con destacada presencia en exhibiciones internacionales - EXPONOR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exponor.cl\/en\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/","og_locale":"en_US","og_type":"article","og_title":"EXPONOR proyecta la miner\u00eda chilena al mundo con destacada presencia en exhibiciones internacionales - EXPONOR","og_description":"La exhibici\u00f3n minero-energ\u00e9tica m\u00e1s importante del pr\u00f3ximo a\u00f1o ha fortalecido su posici\u00f3n global participando en diversos eventos internacionales, promoviendo los avances, la inversi\u00f3n y las oportunidades de colaboraci\u00f3n en la industria minera que se encontrar\u00e1n en EXPONOR 2026. Organizada por la Asociaci\u00f3n de Industriales de Antofagasta (AIA), el evento contin\u00faa consolid\u00e1ndose como una plataforma estrat\u00e9gica [&hellip;]","og_url":"https:\/\/exponor.cl\/en\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/","og_site_name":"EXPONOR","article_publisher":"https:\/\/facebook.com\/exponorcl","article_published_time":"2025-11-06T19:48:46+00:00","og_image":[{"width":800,"height":370,"url":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/08\/Bandera2026.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@exponorcl","twitter_site":"@exponorcl","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/#article","isPartOf":{"@id":"https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/"},"author":{"name":"admin","@id":"https:\/\/exponor.cl\/#\/schema\/person\/f43dbb34f0c1563f0a03fb8fae81a53b"},"headline":"EXPONOR proyecta la miner\u00eda chilena al mundo con destacada presencia en exhibiciones internacionales","datePublished":"2025-11-06T19:48:46+00:00","mainEntityOfPage":{"@id":"https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/"},"wordCount":810,"commentCount":0,"publisher":{"@id":"https:\/\/exponor.cl\/#organization"},"image":{"@id":"https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/08\/Bandera2026.png","articleSection":["Antofagasta","Exhibici\u00f3n","EXPONOR2026"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/","url":"https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/","name":"EXPONOR proyecta la miner\u00eda chilena al mundo con destacada presencia en exhibiciones internacionales - EXPONOR","isPartOf":{"@id":"https:\/\/exponor.cl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/#primaryimage"},"image":{"@id":"https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/08\/Bandera2026.png","datePublished":"2025-11-06T19:48:46+00:00","breadcrumb":{"@id":"https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/#primaryimage","url":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/08\/Bandera2026.png","contentUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/08\/Bandera2026.png","width":800,"height":370},{"@type":"BreadcrumbList","@id":"https:\/\/exponor.cl\/2025\/11\/06\/exponor-proyecta-la-mineria-chilena-al-mundo-con-destacada-presencia-en-exhibiciones-internacionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exponor.cl\/"},{"@type":"ListItem","position":2,"name":"EXPONOR proyecta la miner\u00eda chilena al mundo con destacada presencia en exhibiciones internacionales"}]},{"@type":"WebSite","@id":"https:\/\/exponor.cl\/#website","url":"https:\/\/exponor.cl\/","name":"EXPONOR","description":"Exhibici\u00f3n Internacional de Tecnolog\u00edas e Innovaciones para la Industria Minera y Energ\u00e9tica","publisher":{"@id":"https:\/\/exponor.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exponor.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/exponor.cl\/#organization","name":"EXPONOR","url":"https:\/\/exponor.cl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/exponor.cl\/#\/schema\/logo\/image\/","url":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/03\/EXPONOR2026_confecha.png","contentUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/03\/EXPONOR2026_confecha.png","width":2107,"height":1061,"caption":"EXPONOR"},"image":{"@id":"https:\/\/exponor.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/exponorcl","https:\/\/x.com\/exponorcl","https:\/\/cl.linkedin.com\/company\/exponorcl","https:\/\/www.instagram.com\/exponorcl\/"]},{"@type":"Person","@id":"https:\/\/exponor.cl\/#\/schema\/person\/f43dbb34f0c1563f0a03fb8fae81a53b","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e397b36c8ccaee2f035941656d2bbba67d084ad6aab1abb7717fd9df0594dd0e?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/exponor.cl"],"url":"https:\/\/exponor.cl\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts\/26544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/comments?post=26544"}],"version-history":[{"count":3,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts\/26544\/revisions"}],"predecessor-version":[{"id":26548,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts\/26544\/revisions\/26548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/media\/26087"}],"wp:attachment":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/media?parent=26544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/categories?post=26544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/tags?post=26544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}