{"id":31,"count":17,"description":"","link":"https:\/\/exponor.cl\/en\/category\/seminarios\/","name":"Seminars","slug":"seminarios","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Seminarios archivos - EXPONOR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/exponor.cl\/en\/category\/seminarios\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seminarios archivos - EXPONOR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/exponor.cl\/en\/category\/seminarios\/\" \/>\n<meta property=\"og:site_name\" content=\"EXPONOR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@exponorcl\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/en\\\/category\\\/seminarios\\\/\",\"url\":\"https:\\\/\\\/exponor.cl\\\/en\\\/category\\\/seminarios\\\/\",\"name\":\"Seminarios archivos - EXPONOR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/en\\\/category\\\/seminarios\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/en\\\/category\\\/seminarios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/exponor.cl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seminarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#website\",\"url\":\"https:\\\/\\\/exponor.cl\\\/\",\"name\":\"EXPONOR\",\"description\":\"Exhibici\u00f3n Internacional de Tecnolog\u00edas e Innovaciones para la Industria Minera y Energ\u00e9tica\",\"publisher\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/exponor.cl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#organization\",\"name\":\"EXPONOR\",\"url\":\"https:\\\/\\\/exponor.cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/EXPONOR2026_confecha.png\",\"contentUrl\":\"https:\\\/\\\/exponor.cl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/EXPONOR2026_confecha.png\",\"width\":2107,\"height\":1061,\"caption\":\"EXPONOR\"},\"image\":{\"@id\":\"https:\\\/\\\/exponor.cl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/exponorcl\",\"https:\\\/\\\/x.com\\\/exponorcl\",\"https:\\\/\\\/cl.linkedin.com\\\/company\\\/exponorcl\",\"https:\\\/\\\/www.instagram.com\\\/exponorcl\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seminarios archivos - EXPONOR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/exponor.cl\/en\/category\/seminarios\/","og_locale":"en_US","og_type":"article","og_title":"Seminarios archivos - EXPONOR","og_url":"https:\/\/exponor.cl\/en\/category\/seminarios\/","og_site_name":"EXPONOR","twitter_card":"summary_large_image","twitter_site":"@exponorcl","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/exponor.cl\/en\/category\/seminarios\/","url":"https:\/\/exponor.cl\/en\/category\/seminarios\/","name":"Seminarios archivos - EXPONOR","isPartOf":{"@id":"https:\/\/exponor.cl\/#website"},"breadcrumb":{"@id":"https:\/\/exponor.cl\/en\/category\/seminarios\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/exponor.cl\/en\/category\/seminarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/exponor.cl\/"},{"@type":"ListItem","position":2,"name":"Seminarios"}]},{"@type":"WebSite","@id":"https:\/\/exponor.cl\/#website","url":"https:\/\/exponor.cl\/","name":"EXPONOR","description":"Exhibici\u00f3n Internacional de Tecnolog\u00edas e Innovaciones para la Industria Minera y Energ\u00e9tica","publisher":{"@id":"https:\/\/exponor.cl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/exponor.cl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/exponor.cl\/#organization","name":"EXPONOR","url":"https:\/\/exponor.cl\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/exponor.cl\/#\/schema\/logo\/image\/","url":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/03\/EXPONOR2026_confecha.png","contentUrl":"https:\/\/exponor.cl\/wp-content\/uploads\/2025\/03\/EXPONOR2026_confecha.png","width":2107,"height":1061,"caption":"EXPONOR"},"image":{"@id":"https:\/\/exponor.cl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/exponorcl","https:\/\/x.com\/exponorcl","https:\/\/cl.linkedin.com\/company\/exponorcl","https:\/\/www.instagram.com\/exponorcl\/"]}]}},"_links":{"self":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/categories\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/exponor.cl\/en\/wp-json\/wp\/v2\/posts?categories=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}